{"id":33,"date":"2014-01-04T11:59:20","date_gmt":"2014-01-04T11:59:20","guid":{"rendered":"http:\/\/riodacasca.com.br\/wd\/?p=33"},"modified":"2017-10-16T09:07:19","modified_gmt":"2017-10-16T13:07:19","slug":"um-pouco-de-nossa-historia","status":"publish","type":"post","link":"https:\/\/riodacasca.com.br\/wd\/2014\/01\/04\/um-pouco-de-nossa-historia\/","title":{"rendered":"Um pouco de nossa hist\u00f3ria."},"content":{"rendered":"<p><span style=\"line-height: 1.5em;\">Entrada em opera\u00e7\u00e3o da Usina Hidrel\u00e9trica C\u00e2ndido Rondon ou Casca I, primeira do estado de Mato Grosso. A usina, situada no rio Casca, munic\u00edpio de Chapada dos Guimar\u00e3es, contava com dois grupos geradores de 496 kW cada. Foi desativada em 1954, ano em que entrou em funcionamento a Usina Hidrel\u00e9trica Fernando Correa da Costa ou Casca II.<\/span><\/p>\n<p>A Centrais El\u00e9tricas Matogrossenses, mais tarde Cemat, foi criada em outubro de 1958 com o objetivo de colocar fim a um iminente colapso de suprimento de energia no Estado. No decorrer dos anos, seu trabalho foi ampliado, englobando, al\u00e9m da distribui\u00e7\u00e3o, a constru\u00e7\u00e3o e explora\u00e7\u00e3o de sistemas de gera\u00e7\u00e3o, transmiss\u00e3o e transforma\u00e7\u00e3o.<\/p>\n<p>Em outubro de 1994, a empresa abriu seu capital e, de setembro de 1996 a dezembro do ano seguinte, foi administrada pelo Governo do Estado, em parceria com a Eletrobr\u00e1s e sob a interven\u00e7\u00e3o do BNDES. Estes conduziram o processo de privatiza\u00e7\u00e3o da concession\u00e1ria, que foi comprada pela Rede Energia em leil\u00e3o realizado no dia 27 de novembro de 1997.<\/p>\n<p>AQUI COME\u00c7A A HISTORIA DA PRODU\u00c7\u00c3O ENERG\u00c9TICA DO MATO GROSSO<\/p>\n<p>Em Mato Grosso, antes do surgimento da energia el\u00e9trica, era utilizado o \u00f3leo de piquira (peixe da bacia do pantanal), para a ilumina\u00e7\u00e3o p\u00fablica, especialmente na cidade de Cuiab\u00e1.<br \/>\nAs lumin\u00e1rias eram constitu\u00eddas de tigelas de barro cozido ou cascas de laranja azeda cheias de sebo ou \u00f3leo de piquira, com um pavio torcido. Eram acesas em ocasi\u00f5es importantes como festas, chegada de pol\u00edticos e autoridades.<br \/>\nEsse tipo<span class=\"text_exposed_show\"> de ilumina\u00e7\u00e3o durou at\u00e9 por volta de 1872 e foi substitu\u00eddo pelo candeeiro, um tipo de lampi\u00e3o abastecido com querosene, que por sua vez, foi logo substitu\u00eddo (1873) pelos lampi\u00f5es a g\u00e1s;<br \/>\nCom o advento dos geradores, Cuiab\u00e1 entra na era da energia el\u00e9trica, passando a ser iluminada pelas l\u00e2mpadas de Edison.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>USINA CASCA I<br \/>\nA constru\u00e7\u00e3o da usina hidroel\u00e9trica Casca I no rio da Casca, afluente do rio Manso (Chapada dos Guimar\u00e3es), inaugurada em 1928, foi a primeira medida no sentido de resolver o problema energ\u00e9tico de Cuiab\u00e1.<br \/>\nEntrada em opera\u00e7\u00e3o da Usina Hidrel\u00e9trica C\u00e2ndido Rondon ou Casca I, primeira do estado de Mato Grosso. A usina, situada no rio Casca, munic\u00edpio de Chapada dos Guimar\u00e3es, contava com dois grupos geradores de 496 kW cada.<br \/>\nObra executada no governo do 10\u00ba presidente constitucional do Estado de Mato Grosso o Dr. M\u00e1rio Corr\u00eaa da Costa, que governou de 1926 at\u00e9 1930.<\/p>\n<p>O &#8220;Chal\u00e9 dos Governadores&#8221; e a Usina Casca l foram tombado pelo patrim\u00f4nio hist\u00f3rico de Mato Grosso. (veja tamb\u00e9m este documento) -&gt;<a href=\"https:\/\/www.facebook.com\/riodacasca\/posts\/336248566499295\">https:\/\/www.facebook.com\/riodacasca\/posts\/336248566499295<\/a><\/p>\n<p>Ver mais sobre o Chal\u00e9 dos Governadores. &#8211;&gt;<a href=\"https:\/\/www.facebook.com\/riodacasca\/posts\/335070406617111\">https:\/\/www.facebook.com\/riodacasca\/posts\/335070406617111<\/a><\/p>\n<p>Foto de como era a Usina 1. Ano 1928.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\" wp-image-43 aligncenter\" src=\"https:\/\/riodacasca.com.br\/wd\/wp-content\/uploads\/2014\/01\/Casca1-150x150.jpg\" alt=\"\" width=\"181\" height=\"181\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrada em opera\u00e7\u00e3o da Usina Hidrel\u00e9trica C\u00e2ndido Rondon ou Casca I, primeira do estado de Mato Grosso. A usina, situada no rio Casca, munic\u00edpio de Chapada dos Guimar\u00e3es, contava com dois grupos geradores de 496 kW cada. Foi desativada em 1954, ano em que entrou em funcionamento a Usina Hidrel\u00e9trica Fernando Correa da Costa ou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","two_page_speed":[],"_joinchat":[],"footnotes":""},"categories":[3],"tags":[],"class_list":["post-33","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia"],"_links":{"self":[{"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/posts\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":11,"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"predecessor-version":[{"id":900,"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/posts\/33\/revisions\/900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/media\/43"}],"wp:attachment":[{"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riodacasca.com.br\/wd\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}